{"id":791,"date":"2025-09-22T13:54:37","date_gmt":"2025-09-22T17:54:37","guid":{"rendered":"https:\/\/dianehinesdds.wpenginepowered.com\/?p=791"},"modified":"2026-08-25T09:53:10","modified_gmt":"2026-08-25T13:53:10","slug":"enfermedad-de-las-encias","status":"publish","type":"post","link":"https:\/\/www.aestheticdental.com\/es\/periodontal-disease\/","title":{"rendered":"Enfermedad periodontal"},"content":{"rendered":"<h1 class=\"h2\">Tratamiento integral de la enfermedad de las enc\u00edas en Southfield<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"longdesc-return-792\" class=\"alignright wp-image-792 size-full\" tabindex=\"-1\" src=\"http:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/09\/Periodontal-Disease.jpg\" alt=\"Enfermedad periodontal\" width=\"500\" height=\"264\" longdesc=\"https:\/\/www.aestheticdental.com?longdesc=792&amp;referrer=791\" srcset=\"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/09\/Periodontal-Disease.jpg 500w, https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/09\/Periodontal-Disease-18x10.jpg 18w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\u00bfTe sangran las enc\u00edas al cepillarte los dientes y usar hilo dental? \u00bfEst\u00e1n enrojecidas, inflamadas y te duelen al tocarlas? Si es as\u00ed, es posible que tengas una enfermedad de las enc\u00edas. En Aesthetic Dental, la Dra. Diane Hines y nuestro equipo est\u00e1n comprometidos a proteger tu sonrisa y la salud de tus enc\u00edas a largo plazo. Ofrecemos atenci\u00f3n integral para todas las etapas de la enfermedad de las enc\u00edas en Southfield, West Bloomfield, Franklin y Novi. Nuestra dentista trabaja en colaboraci\u00f3n con un periodoncista local para tratar los problemas m\u00e1s avanzados.<\/p>\n<p>Nuestros tratamientos disponibles incluyen raspado y alisado radicular, antibi\u00f3ticos ARESTIN, l\u00e1seres para tejidos blandos y ex\u00e1menes de mantenimiento continuos y evaluaciones del tejido gingival. Al combinar la experiencia con t\u00e9cnicas confiables, podemos detectar, diagnosticar y prevenir la enfermedad de las enc\u00edas.<\/p>\n<p>Trabajamos duro para mantener sus dientes y enc\u00edas sanos con servicios que hacen hincapi\u00e9 en la educaci\u00f3n y la personalizaci\u00f3n. Puede confiar en nosotros para ayudarle a recuperar la salud de sus enc\u00edas. \u00a1P\u00f3ngase en contacto con Aesthetic Dental hoy mismo si usted o un ser querido padecen de enfermedad de las enc\u00edas!<\/p>\n<h2 class=\"h3\">\u00bfQu\u00e9 es la enfermedad de las enc\u00edas?<\/h2>\n<p>La enfermedad de las enc\u00edas es una infecci\u00f3n bucal que inflama y ataca las enc\u00edas, los tejidos, los ligamentos y las ra\u00edces dentales responsables de mantener los dientes en su lugar. Aunque la causa m\u00e1s com\u00fan de la infecci\u00f3n de las enc\u00edas es el exceso de placa y la acumulaci\u00f3n de sarro, la afecci\u00f3n puede desarrollarse debido a otros factores. Entre ellos se incluyen la gen\u00e9tica, la dieta, el tabaquismo, el consumo excesivo de alcohol, el uso de medicamentos, enfermedades sist\u00e9micas como la diabetes y otros.<\/p>\n<p>La placa contiene bacterias y toxinas que se forman en los dientes, por encima y por debajo de la l\u00ednea de las enc\u00edas. Esta acumulaci\u00f3n acaba provocando enfermedad de las enc\u00edas, una afecci\u00f3n com\u00fan pero grave que puede afectar a su salud bucal y a su bienestar general. La enfermedad grave de las enc\u00edas, clasificada como periodontitis avanzada, es la principal causa de p\u00e9rdida de dientes.<\/p>\n<h3 class=\"h4\">7 signos y s\u00edntomas de la enfermedad de las enc\u00edas<\/h3>\n<p>Los primeros signos de la enfermedad de las enc\u00edas suelen pasarse por alto debido a que los s\u00edntomas y molestias son leves. Los siete s\u00edntomas m\u00e1s comunes de la enfermedad de las enc\u00edas son:<\/p>\n<ol class=\"split-list\">\n<li>Enc\u00edas rojas brillantes, inflamadas y sensibles.<\/li>\n<li>Sangrado de las enc\u00edas al cepillarse los dientes y usar hilo dental<\/li>\n<li>Sensibilidad dental al fr\u00edo y al calor<\/li>\n<li>Dolor al masticar o morder<\/li>\n<li>Dientes flojos<\/li>\n<li>Mal aliento persistente o mal sabor de boca<\/li>\n<li>Dientes que parecen m\u00e1s largos debido al retroceso del tejido gingival.<\/li>\n<\/ol>\n<h2 class=\"h3\">\u00bfPuede la enfermedad de las enc\u00edas afectar mi salud en general?<\/h2>\n<p>S\u00ed. Cada vez m\u00e1s investigaciones m\u00e9dicas y odontol\u00f3gicas sugieren que la infecci\u00f3n bacteriana asociada a la enfermedad de las enc\u00edas puede extenderse m\u00e1s all\u00e1 de la boca y, si no se trata adecuadamente, acabar provocando problemas de salud generales. Esto es posible porque la salud bucal y el bienestar general est\u00e1n estrechamente relacionados a trav\u00e9s de una conexi\u00f3n conocida como conexi\u00f3n bucal-sist\u00e9mica.<\/p>\n<p>Las mismas toxinas que causan la inflamaci\u00f3n de las enc\u00edas pueden llegar al torrente sangu\u00edneo a medida que se forma placa y sarro m\u00e1s da\u00f1inos debajo de la l\u00ednea de las enc\u00edas. A medida que la infecci\u00f3n entra en el torrente sangu\u00edneo, tambi\u00e9n puede acceder a otras \u00e1reas del cuerpo. Se sabe que la enfermedad avanzada de las enc\u00edas causa complicaciones con enfermedades card\u00edacas, diabetes y dificultades durante el embarazo.<\/p>\n<h3 class=\"h4\">Protegi\u00e9ndote con prevenci\u00f3n a trav\u00e9s de la educaci\u00f3n<\/h3>\n<p>El Dr. Hines y nuestro equipo creen que una de las mejores maneras de ayudar a mantener su sonrisa libre de enfermedades de las enc\u00edas es mediante la prevenci\u00f3n proactiva y la educaci\u00f3n. Nuestro objetivo es ayudarle a conservar sus dientes naturales y mantener sus enc\u00edas sanas ense\u00f1\u00e1ndole c\u00f3mo cuidar su salud bucal.<\/p>\n<p>Nos tomamos el tiempo necesario para revisar su historial m\u00e9dico y le informamos sobre nuestros hallazgos durante la exploraci\u00f3n. De esta manera, nuestro equipo puede informarle sobre su situaci\u00f3n actual en cada paso del proceso. Nuestra dentista le explica las formas correctas de cepillarse los dientes, usar hilo dental y cuidar su sonrisa entre visitas. Tambi\u00e9n repasa sus posibles factores de riesgo y le informa sobre las enfermedades sist\u00e9micas relacionadas.<\/p>\n<h2 class=\"h3\">Tratamiento de la enfermedad de las enc\u00edas en St. George<\/h2>\n<p>Ofrecemos cuidados dise\u00f1ados para detectar, diagnosticar y reducir las enfermedades de las enc\u00edas combinando servicios integrales y tecnolog\u00eda avanzada. Nuestro equipo ofrece limpiezas profundas o raspado y alisado radicular para las enfermedades de las enc\u00edas. El tratamiento nos permite eliminar el sarro, la placa y otros subproductos nocivos. Realizamos limpiezas profundas en Southfield despu\u00e9s de un examen y una evaluaci\u00f3n exhaustivos de su sonrisa.<\/p>\n<p>Utilizamos herramientas especiales para eliminar el exceso de sarro y placa de forma minuciosa y cuidadosa. El raspado dental consiste en limpiar la superficie de los dientes y las zonas situadas debajo de la l\u00ednea de las enc\u00edas. De este modo, nuestro equipo puede eliminar la placa y las bacterias de todas las superficies. Alisamos las ra\u00edces dentales para favorecer la cicatrizaci\u00f3n adecuada y la readhesi\u00f3n del tejido gingival a los dientes.<\/p>\n<h3 class=\"h4\">Nuestro enfoque integral para el tratamiento de las enc\u00edas<\/h3>\n<p>Los l\u00e1seres para tejidos blandos nos permiten eliminar la infecci\u00f3n y extirpar el tejido gingival enfermo sin bistur\u00eds y sin da\u00f1ar las estructuras sanas circundantes. A menudo, podemos combinar el tratamiento con l\u00e1ser con antibi\u00f3ticos ARESTIN para reducir las bolsas gingivales. Nuestro dentista puede recetarle un enjuague seg\u00fan sea necesario para ayudar a proteger y mantener la salud de sus enc\u00edas en casa.<\/p>\n<p>Hacemos todo lo posible para eliminar la enfermedad de forma segura y eficaz, ayudando a preparar su sonrisa para otros tratamientos, como restauraciones o extracciones, si fuera necesario. El Dr. Hines tambi\u00e9n puede recetarle un enjuague para la boca seca si esto est\u00e1 afectando a la salud de sus enc\u00edas a largo plazo.<\/p>\n<h3 class=\"h4\">\u00bfCon qu\u00e9 frecuencia necesito realizar el mantenimiento?<\/h3>\n<p>El mantenimiento continuo, como las limpiezas profundas y los ex\u00e1menes del tejido gingival, puede requerir que visite nuestro consultorio cada tres o cuatro meses. Es posible que le recomendemos que acuda antes si ha recibido tratamiento para periodontitis avanzada o tiene antecedentes de enfermedad de las enc\u00edas. Nuestro dentista crear\u00e1 un plan basado en la gravedad de su afecci\u00f3n y en c\u00f3mo responden sus enc\u00edas al tratamiento anterior.<\/p>\n<h2 class=\"h3\">\u00a1Proteja la salud de sus enc\u00edas y dientes hoy mismo!<\/h2>\n<p>En Aesthetic Dental, la Dra. Diane Hines ofrece un tratamiento integral y mantenimiento de las enfermedades de las enc\u00edas en Southfield, West Bloomfield, Franklin y Novi. Creemos que todas las personas, tanto j\u00f3venes como mayores, merecen disfrutar de una sonrisa bonita y saludable, libre de infecciones. Si cree que puede padecer una enfermedad de las enc\u00edas, \u00a1no lo dude! \u00a1P\u00f3ngase en contacto con nosotros para programar una consulta hoy mismo!<\/p>","protected":false},"excerpt":{"rendered":"<p>Comprehensive Gum Disease Treatment in Southfield Do your gums bleed during regular brushing and flossing? Are they red, swollen, and tender to the touch? If so, you may have gum disease. At Aesthetic Dental, Dr. Diane Hines and our team are committed to protecting your smile and long-term gum health. We provide comprehensive care for [&#8230;]\n","protected":false},"author":7,"featured_media":792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"gmb_109265489736877664202_accounts\/109265489736877664202\/locations\/16295114870047390508":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1,132],"tags":[],"class_list":["post-791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aesthetic-dental-blog","category-gum-disease"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Periodontal Disease Treatment \ud83e\uddb7 | Aesthetic Dental Southfield, MI<\/title>\n<meta name=\"description\" content=\"Protect your gums and overall health. Aesthetic Dental in Southfield offers periodontal disease care to stop gum disease &amp; save your smile.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aestheticdental.com\/es\/enfermedad-de-las-encias\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Periodontal Disease Treatment \ud83e\uddb7 | Aesthetic Dental Southfield, MI\" \/>\n<meta property=\"og:description\" content=\"Protect your gums and overall health. Aesthetic Dental in Southfield offers periodontal disease care to stop gum disease &amp; save your smile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aestheticdental.com\/es\/enfermedad-de-las-encias\/\" \/>\n<meta property=\"og:site_name\" content=\"Aesthetic Dental\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T17:54:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-25T13:53:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/09\/Periodontal-Disease.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aesthetic Dental\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aesthetic Dental\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/\"},\"author\":{\"name\":\"Aesthetic Dental\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/#\\\/schema\\\/person\\\/1f04b8979e5799079ebfe75ed773703e\"},\"headline\":\"Periodontal Disease\",\"datePublished\":\"2025-09-22T17:54:37+00:00\",\"dateModified\":\"2026-08-25T13:53:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/\"},\"wordCount\":942,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aestheticdental.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Periodontal-Disease.jpg\",\"articleSection\":[\"Aesthetic Dental Blog\",\"Gum Disease\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/\",\"url\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/\",\"name\":\"Periodontal Disease Treatment \ud83e\uddb7 | Aesthetic Dental Southfield, MI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aestheticdental.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Periodontal-Disease.jpg\",\"datePublished\":\"2025-09-22T17:54:37+00:00\",\"dateModified\":\"2026-08-25T13:53:10+00:00\",\"description\":\"Protect your gums and overall health. Aesthetic Dental in Southfield offers periodontal disease care to stop gum disease & save your smile.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aestheticdental.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Periodontal-Disease.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aestheticdental.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Periodontal-Disease.jpg\",\"width\":500,\"height\":264,\"caption\":\"Periodontal Disease Treatment \ud83e\uddb7 | Aesthetic Dental Southfield, MI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/periodontal-disease\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aestheticdental.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Periodontal Disease\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/#website\",\"url\":\"https:\\\/\\\/www.aestheticdental.com\\\/\",\"name\":\"Aesthetic Dental | General, Cosmetic & Implant Dentistry in Southfield, MI\",\"description\":\"General, Cosmetic &amp; Implant Dentistry in Southfield, MI\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aestheticdental.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/#organization\",\"name\":\"Aesthetic Dental | General, Cosmetic & Implant Dentistry in Southfield, MI\",\"url\":\"https:\\\/\\\/www.aestheticdental.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aestheticdental.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Aesthetic-Dental-Square-Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aestheticdental.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Aesthetic-Dental-Square-Logo.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Aesthetic Dental | General, Cosmetic & Implant Dentistry in Southfield, MI\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/#\\\/schema\\\/person\\\/1f04b8979e5799079ebfe75ed773703e\",\"name\":\"Aesthetic Dental\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.aestheticdental.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Dr.-Diane-Hines-Aesthetic-Dental-Southfield-MI-280x280.jpg\",\"url\":\"https:\\\/\\\/www.aestheticdental.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Dr.-Diane-Hines-Aesthetic-Dental-Southfield-MI-280x280.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aestheticdental.com\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/Dr.-Diane-Hines-Aesthetic-Dental-Southfield-MI-280x280.jpg\",\"caption\":\"Aesthetic Dental\"},\"description\":\"Aesthetic Dental is passionate about improving the oral health of patients in our community. It is our goal to educate, inform and care for all of our patients in a gentle and caring manner. We strive to provide the best customer experience possible with the very latest advancements in dental technology. We partner with our patients to provide the healthiest most beautiful smiles modern dentistry can offer.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tratamiento de la enfermedad periodontal \ud83e\uddb7 | Aesthetic Dental Southfield, M\u00edchigan","description":"Proteja sus enc\u00edas y su salud en general. Aesthetic Dental en Southfield ofrece tratamiento para la enfermedad periodontal con el fin de detener la enfermedad de las enc\u00edas y salvar su sonrisa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aestheticdental.com\/es\/enfermedad-de-las-encias\/","og_locale":"es_MX","og_type":"article","og_title":"Periodontal Disease Treatment \ud83e\uddb7 | Aesthetic Dental Southfield, MI","og_description":"Protect your gums and overall health. Aesthetic Dental in Southfield offers periodontal disease care to stop gum disease & save your smile.","og_url":"https:\/\/www.aestheticdental.com\/es\/enfermedad-de-las-encias\/","og_site_name":"Aesthetic Dental","article_published_time":"2025-09-22T17:54:37+00:00","article_modified_time":"2026-08-25T13:53:10+00:00","og_image":[{"width":500,"height":264,"url":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/09\/Periodontal-Disease.jpg","type":"image\/jpeg"}],"author":"Aesthetic Dental","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Aesthetic Dental","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/#article","isPartOf":{"@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/"},"author":{"name":"Aesthetic Dental","@id":"https:\/\/www.aestheticdental.com\/#\/schema\/person\/1f04b8979e5799079ebfe75ed773703e"},"headline":"Periodontal Disease","datePublished":"2025-09-22T17:54:37+00:00","dateModified":"2026-08-25T13:53:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/"},"wordCount":942,"publisher":{"@id":"https:\/\/www.aestheticdental.com\/#organization"},"image":{"@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/09\/Periodontal-Disease.jpg","articleSection":["Aesthetic Dental Blog","Gum Disease"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/","url":"https:\/\/www.aestheticdental.com\/periodontal-disease\/","name":"Tratamiento de la enfermedad periodontal \ud83e\uddb7 | Aesthetic Dental Southfield, M\u00edchigan","isPartOf":{"@id":"https:\/\/www.aestheticdental.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/#primaryimage"},"image":{"@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/09\/Periodontal-Disease.jpg","datePublished":"2025-09-22T17:54:37+00:00","dateModified":"2026-08-25T13:53:10+00:00","description":"Proteja sus enc\u00edas y su salud en general. Aesthetic Dental en Southfield ofrece tratamiento para la enfermedad periodontal con el fin de detener la enfermedad de las enc\u00edas y salvar su sonrisa.","breadcrumb":{"@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aestheticdental.com\/periodontal-disease\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/#primaryimage","url":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/09\/Periodontal-Disease.jpg","contentUrl":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/09\/Periodontal-Disease.jpg","width":500,"height":264,"caption":"Periodontal Disease Treatment \ud83e\uddb7 | Aesthetic Dental Southfield, MI"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aestheticdental.com\/periodontal-disease\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aestheticdental.com\/"},{"@type":"ListItem","position":2,"name":"Periodontal Disease"}]},{"@type":"WebSite","@id":"https:\/\/www.aestheticdental.com\/#website","url":"https:\/\/www.aestheticdental.com\/","name":"Odontolog\u00eda est\u00e9tica | Odontolog\u00eda general, cosm\u00e9tica e implantes dentales en Southfield, M\u00edchigan","description":"Odontolog\u00eda general, cosm\u00e9tica e implantes dentales en Southfield, M\u00edchigan","publisher":{"@id":"https:\/\/www.aestheticdental.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aestheticdental.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.aestheticdental.com\/#organization","name":"Odontolog\u00eda est\u00e9tica | Odontolog\u00eda general, cosm\u00e9tica e implantes dentales en Southfield, M\u00edchigan","url":"https:\/\/www.aestheticdental.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aestheticdental.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/10\/Aesthetic-Dental-Square-Logo.jpg","contentUrl":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2025\/10\/Aesthetic-Dental-Square-Logo.jpg","width":1000,"height":1000,"caption":"Aesthetic Dental | General, Cosmetic & Implant Dentistry in Southfield, MI"},"image":{"@id":"https:\/\/www.aestheticdental.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.aestheticdental.com\/#\/schema\/person\/1f04b8979e5799079ebfe75ed773703e","name":"Odontolog\u00eda est\u00e9tica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2026\/08\/Dr.-Diane-Hines-Aesthetic-Dental-Southfield-MI-280x280.jpg","url":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2026\/08\/Dr.-Diane-Hines-Aesthetic-Dental-Southfield-MI-280x280.jpg","contentUrl":"https:\/\/www.aestheticdental.com\/wp-content\/uploads\/2026\/08\/Dr.-Diane-Hines-Aesthetic-Dental-Southfield-MI-280x280.jpg","caption":"Aesthetic Dental"},"description":"En Aesthetic Dental nos apasiona mejorar la salud bucal de los pacientes de nuestra comunidad. Nuestro objetivo es educar, informar y atender a todos nuestros pacientes de forma amable y atenta. Nos esforzamos por ofrecer la mejor experiencia posible al cliente con los \u00faltimos avances en tecnolog\u00eda dental. Colaboramos con nuestros pacientes para proporcionarles las sonrisas m\u00e1s sanas y bonitas que la odontolog\u00eda moderna puede ofrecer."}]}},"_links":{"self":[{"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/posts\/791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/comments?post=791"}],"version-history":[{"count":1,"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/posts\/791\/revisions"}],"predecessor-version":[{"id":2316,"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/posts\/791\/revisions\/2316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/media\/792"}],"wp:attachment":[{"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/media?parent=791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/categories?post=791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aestheticdental.com\/es\/wp-json\/wp\/v2\/tags?post=791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}